{"id":64,"date":"2026-01-03T12:36:06","date_gmt":"2026-01-03T11:36:06","guid":{"rendered":"https:\/\/www.sanktgabriel.de\/?page_id=64"},"modified":"2026-04-02T23:11:47","modified_gmt":"2026-04-02T21:11:47","slug":"home","status":"publish","type":"page","link":"https:\/\/www.sanktgabriel.de\/","title":{"rendered":"Willkommen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hier stellt sich die Pfarrgemeinde St. Gabriel in M\u00fcnchen-Haidhausen mit ihren vielf\u00e4ltigen Aktivit\u00e4ten vor. Nehmen Sie sich Zeit f\u00fcr einen Blick auf die Vielfalt der Gemeinde! Wenn Sie sich einbringen wollen, wenden Sie sich bitte an die entsprechenden Verantwortlichen. Wir freuen uns \u00fcber jeden, der zum Gelingen der Gemeinschaft beitr\u00e4gt.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Kirche_innen_StGabriel.jpg\" alt=\"\" class=\"wp-image-36\" srcset=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Kirche_innen_StGabriel.jpg 600w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Kirche_innen_StGabriel-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><br>100 Jahre Sankt Gabriel<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bitte klicken Sie auf das Bild, um zur Infoseite zu gelangen!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.sanktgabriel.de\/index.php\/100-jahre-st-gabriel\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"991\" src=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/02\/StGabriel_Logo-1024x991.png\" alt=\"\" class=\"wp-image-750\" srcset=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/02\/StGabriel_Logo-1024x991.png 1024w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/02\/StGabriel_Logo-300x290.png 300w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/02\/StGabriel_Logo-768x743.png 768w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/02\/StGabriel_Logo-310x300.png 310w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/02\/StGabriel_Logo.png 1052w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\">Neueste Beitr\u00e4ge<\/h1>\n\n\n<div id=\"psacp-post-carousel-wrap-1\" class=\"psacp-wrap psacp-post-carousel-wrap owl-carousel psacp-design-1 psacp-layout-611 psacp-has-arrows psacp-clearfix\" data-conf=\"{&quot;slide_show&quot;:2,&quot;loop&quot;:true,&quot;arrows&quot;:true,&quot;dots&quot;:true,&quot;autoplay&quot;:true,&quot;autoplay_interval&quot;:5000,&quot;speed&quot;:500,&quot;slide_scroll&quot;:1,&quot;rtl&quot;:false}\"><div class=\"psacp-post-slide psacp-post-1009 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-carousel-content\">\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Bildschirmfoto-2026-04-23-um-23.07.09-500x500.png);\">\r\n\t\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/08\/11\/2-engel-fuer-die-prinzregentenstrasse\/\"><\/a>\r\n\t\t\t<div class=\"psacp-post-overlay\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"psacp-post-cats\"><a class=\"psacp-post-cat-link psacp-post-cat-1\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/category\/allgemein\/\">Allgemein<\/a><\/div>\r\n\t\t\t\t\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/08\/11\/2-engel-fuer-die-prinzregentenstrasse\/\">2 Engel f\u00fcr die Prinzregentenstra\u00dfe<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-author\"><i class=\"psacp-fa fa-solid fa-user\"><\/i>Siegfried<\/span><span class=\"psacp-post-meta-sep\"> &ndash; <\/span><span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"psacp-fa fa-regular fa-clock\"><\/i>11 August, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\r\n\t\t\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-997 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-carousel-content\">\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/08\/Bildschirmfoto-2026-08-03-um-00.06.47-1-1024x736.png);\">\r\n\t\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/08\/03\/kleiderkammer-im-august\/\"><\/a>\r\n\t\t\t<div class=\"psacp-post-overlay\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"psacp-post-cats\"><a class=\"psacp-post-cat-link psacp-post-cat-1\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/category\/allgemein\/\">Allgemein<\/a><\/div>\r\n\t\t\t\t\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/08\/03\/kleiderkammer-im-august\/\">Kleiderkammer ist in den Sommerferien geschlossen<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-author\"><i class=\"psacp-fa fa-solid fa-user\"><\/i>Siegfried<\/span><span class=\"psacp-post-meta-sep\"> &ndash; <\/span><span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"psacp-fa fa-regular fa-clock\"><\/i>3 August, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\r\n\t\t\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-956 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-carousel-content\">\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/06\/Bildschirmfoto-2026-06-23-um-16.16.27-500x500.png);\">\r\n\t\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/06\/23\/kinderfest-in-st-gabriel\/\"><\/a>\r\n\t\t\t<div class=\"psacp-post-overlay\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"psacp-post-cats\"><a class=\"psacp-post-cat-link psacp-post-cat-1\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/category\/allgemein\/\">Allgemein<\/a><\/div>\r\n\t\t\t\t\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/06\/23\/kinderfest-in-st-gabriel\/\">Kinderfest in St. Gabriel<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-author\"><i class=\"psacp-fa fa-solid fa-user\"><\/i>Siegfried<\/span><span class=\"psacp-post-meta-sep\"> &ndash; <\/span><span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"psacp-fa fa-regular fa-clock\"><\/i>23 Juni, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\r\n\t\t\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-871 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-carousel-content\">\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Bildschirmfoto-2026-04-23-um-23.07.09-500x500.png);\">\r\n\t\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/04\/23\/kirchenmusik-2026\/\"><\/a>\r\n\t\t\t<div class=\"psacp-post-overlay\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"psacp-post-cats\"><a class=\"psacp-post-cat-link psacp-post-cat-1\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/category\/allgemein\/\">Allgemein<\/a><\/div>\r\n\t\t\t\t\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/04\/23\/kirchenmusik-2026\/\">Kirchenmusik 2026<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-author\"><i class=\"psacp-fa fa-solid fa-user\"><\/i>Siegfried<\/span><span class=\"psacp-post-meta-sep\"> &ndash; <\/span><span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"psacp-fa fa-regular fa-clock\"><\/i>23 April, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\r\n\t\t\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-868 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-carousel-content\">\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Bildschirmfoto-2026-04-23-um-23.07.09-500x500.png);\">\r\n\t\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/04\/23\/projektchor\/\"><\/a>\r\n\t\t\t<div class=\"psacp-post-overlay\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"psacp-post-cats\"><a class=\"psacp-post-cat-link psacp-post-cat-1\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/category\/allgemein\/\">Allgemein<\/a><\/div>\r\n\t\t\t\t\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/04\/23\/projektchor\/\">Projektchor zum Jubil\u00e4um<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-author\"><i class=\"psacp-fa fa-solid fa-user\"><\/i>Siegfried<\/span><span class=\"psacp-post-meta-sep\"> &ndash; <\/span><span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"psacp-fa fa-regular fa-clock\"><\/i>23 April, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\r\n\t\t\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-822 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-carousel-content\">\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/Werde-KirchenkuenstlerIn_Plakat-1.png);\">\r\n\t\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/03\/24\/werde-kirchenkuenstlerin\/\"><\/a>\r\n\t\t\t<div class=\"psacp-post-overlay\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"psacp-post-cats\"><a class=\"psacp-post-cat-link psacp-post-cat-1\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/category\/allgemein\/\">Allgemein<\/a><\/div>\r\n\t\t\t\t\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/03\/24\/werde-kirchenkuenstlerin\/\">Werde Kirchenk\u00fcnstler*in<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-author\"><i class=\"psacp-fa fa-solid fa-user\"><\/i>Siegfried<\/span><span class=\"psacp-post-meta-sep\"> &ndash; <\/span><span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"psacp-fa fa-regular fa-clock\"><\/i>24 M\u00e4rz, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\r\n\t\t\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-718 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-carousel-content\">\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/02\/Bildschirmfoto-2026-02-04-um-00.06.11-500x500.png);\">\r\n\t\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/02\/04\/kindergartenplaetze-frei\/\"><\/a>\r\n\t\t\t<div class=\"psacp-post-overlay\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"psacp-post-cats\"><a class=\"psacp-post-cat-link psacp-post-cat-1\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/category\/allgemein\/\">Allgemein<\/a><\/div>\r\n\t\t\t\t\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/02\/04\/kindergartenplaetze-frei\/\">Kindergartenpl\u00e4tze frei<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-author\"><i class=\"psacp-fa fa-solid fa-user\"><\/i>Siegfried<\/span><span class=\"psacp-post-meta-sep\"> &ndash; <\/span><span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"psacp-fa fa-regular fa-clock\"><\/i>4 Februar, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\r\n\t\t\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-632 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-carousel-content\">\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/VR_Freitag-771x1024.jpg);\">\r\n\t\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/01\/08\/gruppenstunde-fuer-kinder-von-8-bis-12\/\"><\/a>\r\n\t\t\t<div class=\"psacp-post-overlay\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"psacp-post-cats\"><a class=\"psacp-post-cat-link psacp-post-cat-1\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/category\/allgemein\/\">Allgemein<\/a><\/div>\r\n\t\t\t\t\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/01\/08\/gruppenstunde-fuer-kinder-von-8-bis-12\/\">Gruppenstunde f\u00fcr Kinder von 8 bis 12<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-author\"><i class=\"psacp-fa fa-solid fa-user\"><\/i>Siegfried<\/span><span class=\"psacp-post-meta-sep\"> &ndash; <\/span><span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"psacp-fa fa-regular fa-clock\"><\/i>8 Januar, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\r\n\t\t\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-620 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-carousel-content\">\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/KrippeSG2-1024x768.jpg);\">\r\n\t\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/01\/08\/krippe-der-jugendlichen\/\"><\/a>\r\n\t\t\t<div class=\"psacp-post-overlay\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"psacp-post-cats\"><a class=\"psacp-post-cat-link psacp-post-cat-1\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/category\/allgemein\/\">Allgemein<\/a><\/div>\r\n\t\t\t\t\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/01\/08\/krippe-der-jugendlichen\/\">Gro\u00dfe Krippe<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-author\"><i class=\"psacp-fa fa-solid fa-user\"><\/i>Siegfried<\/span><span class=\"psacp-post-meta-sep\"> &ndash; <\/span><span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"psacp-fa fa-regular fa-clock\"><\/i>8 Januar, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\r\n\t\t\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-452 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-carousel-content\">\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Schutzkonzept-1024x656.png);\">\r\n\t\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/01\/04\/praeventionsschutzkonzept\/\"><\/a>\r\n\t\t\t<div class=\"psacp-post-overlay\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"psacp-post-cats\"><a class=\"psacp-post-cat-link psacp-post-cat-1\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/category\/allgemein\/\">Allgemein<\/a><\/div>\r\n\t\t\t\t\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/01\/04\/praeventionsschutzkonzept\/\">Pr\u00e4ventionsschutzkonzept<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-author\"><i class=\"psacp-fa fa-solid fa-user\"><\/i>Siegfried<\/span><span class=\"psacp-post-meta-sep\"> &ndash; <\/span><span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"psacp-fa fa-regular fa-clock\"><\/i>4 Januar, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\r\n\t\t\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-447 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-carousel-content\">\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Missbrauch-737x1024.png);\">\r\n\t\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/01\/04\/unterstuetzung-fuer-betroffene-sexuellen-missbrauchs\/\"><\/a>\r\n\t\t\t<div class=\"psacp-post-overlay\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"psacp-post-cats\"><a class=\"psacp-post-cat-link psacp-post-cat-1\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/category\/allgemein\/\">Allgemein<\/a><\/div>\r\n\t\t\t\t\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/01\/04\/unterstuetzung-fuer-betroffene-sexuellen-missbrauchs\/\">Unterst\u00fctzung f\u00fcr Betroffene\u00a0sexuellen Missbrauchs<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-author\"><i class=\"psacp-fa fa-solid fa-user\"><\/i>Siegfried<\/span><span class=\"psacp-post-meta-sep\"> &ndash; <\/span><span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"psacp-fa fa-regular fa-clock\"><\/i>4 Januar, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\r\n\t\t\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-422 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-carousel-content\">\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Seniorencentrum_Termine-2-696x1024.png);\">\r\n\t\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/01\/04\/gottesdienst-im-seniorencentrum-domicil\/\"><\/a>\r\n\t\t\t<div class=\"psacp-post-overlay\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"psacp-post-cats\"><a class=\"psacp-post-cat-link psacp-post-cat-1\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/category\/allgemein\/\">Allgemein<\/a><\/div>\r\n\t\t\t\t\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/01\/04\/gottesdienst-im-seniorencentrum-domicil\/\">Gottesdienste im Seniorencentrum Domicil<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-author\"><i class=\"psacp-fa fa-solid fa-user\"><\/i>Siegfried<\/span><span class=\"psacp-post-meta-sep\"> &ndash; <\/span><span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"psacp-fa fa-regular fa-clock\"><\/i>4 Januar, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\r\n\t\t\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-181 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-carousel-content\">\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Ehrenamtliche_VR-729x1024.png);\">\r\n\t\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/01\/03\/leben-und-feiern-mit-dem-wort-gottes-veranstaltungsreihe-fuer-ehrenamtliche\/\"><\/a>\r\n\t\t\t<div class=\"psacp-post-overlay\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"psacp-post-cats\"><a class=\"psacp-post-cat-link psacp-post-cat-1\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/category\/allgemein\/\">Allgemein<\/a> <a class=\"psacp-post-cat-link psacp-post-cat-19\" href=\"https:\/\/www.sanktgabriel.de\/index.php\/category\/termine\/veranstaltung\/\">Veranstaltungen<\/a><\/div>\r\n\t\t\t\t\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/01\/03\/leben-und-feiern-mit-dem-wort-gottes-veranstaltungsreihe-fuer-ehrenamtliche\/\">Leben und Feiern mit dem Wort Gottes &#8211; Veranstaltungsreihe f\u00fcr Ehrenamtliche<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-author\"><i class=\"psacp-fa fa-solid fa-user\"><\/i>Siegfried<\/span><span class=\"psacp-post-meta-sep\"> &ndash; <\/span><span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"psacp-fa fa-regular fa-clock\"><\/i>3 Januar, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\r\n\t\t\t<\/div>\r\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressionen aus den Gottesdiensten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Jesus-zieht-auf-einem-Esel-in-Jerusalem-ein-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"839\" src=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Jesus-zieht-auf-einem-Esel-in-Jerusalem-ein-1-768x1024.jpg\" alt=\"\" class=\"wp-image-839\" srcset=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Jesus-zieht-auf-einem-Esel-in-Jerusalem-ein-1-768x1024.jpg 768w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Jesus-zieht-auf-einem-Esel-in-Jerusalem-ein-1-225x300.jpg 225w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Jesus-zieht-auf-einem-Esel-in-Jerusalem-ein-1-1152x1536.jpg 1152w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Jesus-zieht-auf-einem-Esel-in-Jerusalem-ein-1-1536x2048.jpg 1536w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Jesus-zieht-auf-einem-Esel-in-Jerusalem-ein-1-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\">Jesus zieht auf einem Esel in Jerusalem ein (29.3.26)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Jesus-feiert-das-Letzte-Abendmahl-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"838\" src=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Jesus-feiert-das-Letzte-Abendmahl-768x1024.jpg\" alt=\"\" class=\"wp-image-838\" srcset=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Jesus-feiert-das-Letzte-Abendmahl-768x1024.jpg 768w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Jesus-feiert-das-Letzte-Abendmahl-225x300.jpg 225w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Jesus-feiert-das-Letzte-Abendmahl-1152x1536.jpg 1152w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Jesus-feiert-das-Letzte-Abendmahl-1536x2048.jpg 1536w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Jesus-feiert-das-Letzte-Abendmahl-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\">Jesus feiert das Letzte Abendmahl (29.3.26)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Das-Grab-ist-leer-Leid-und-Tod-sind-ueberwunden-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"840\" src=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Das-Grab-ist-leer-Leid-und-Tod-sind-ueberwunden-768x1024.jpg\" alt=\"\" class=\"wp-image-840\" srcset=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Das-Grab-ist-leer-Leid-und-Tod-sind-ueberwunden-768x1024.jpg 768w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Das-Grab-ist-leer-Leid-und-Tod-sind-ueberwunden-225x300.jpg 225w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Das-Grab-ist-leer-Leid-und-Tod-sind-ueberwunden-1152x1536.jpg 1152w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Das-Grab-ist-leer-Leid-und-Tod-sind-ueberwunden-1536x2048.jpg 1536w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/04\/Das-Grab-ist-leer-Leid-und-Tod-sind-ueberwunden-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\">Das Grab ist leer &#8211; Leid und Tod sind u\u0308berwunden (29.3.26)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112833-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"797\" src=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112833-1-768x1024.jpg\" alt=\"\" class=\"wp-image-797\" srcset=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112833-1-768x1024.jpg 768w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112833-1-225x300.jpg 225w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112833-1-1152x1536.jpg 1152w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112833-1-1536x2048.jpg 1536w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112833-1-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\">Kindergottesdienst \u201eNigeria \u2013 Land der Gegens\u00e4tze\u201c \u2013 8.3.26<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112944-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"795\" src=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112944-1-768x1024.jpg\" alt=\"\" class=\"wp-image-795\" srcset=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112944-1-768x1024.jpg 768w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112944-1-225x300.jpg 225w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112944-1-1152x1536.jpg 1152w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112944-1-1536x2048.jpg 1536w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112944-1-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/20260308_112944-1-scaled.jpg\" data-type=\"attachment\" data-id=\"795\">20260308_112944<\/a>Kindergottesdienst \u201eNigeria \u2013 Land der Gegens\u00e4tze\u201c \u2013 8.3.26<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/Caritas-Aktion-2026-rotated.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"801\" src=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/Caritas-Aktion-2026-rotated.jpg\" alt=\"\" class=\"wp-image-801\" srcset=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/Caritas-Aktion-2026-rotated.jpg 1024w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/Caritas-Aktion-2026-300x225.jpg 300w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/Caritas-Aktion-2026-768x576.jpg 768w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/Caritas-Aktion-2026-400x300.jpg 400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/Caritas-Aktion-2026-rotated.jpg\" data-type=\"attachment\" data-id=\"801\">Caritas-Aktion 2026<\/a>Caritas-Gottesdienst &#8222;Zusammen geht was &#8211; Caritas verbindet Generationen&#8220; am 7. M\u00e4rz 2026<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/Caritas-Gottesdienst-07-03-2026-rotated.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"800\" src=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/Caritas-Gottesdienst-07-03-2026-rotated.jpg\" alt=\"\" class=\"wp-image-800\" srcset=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/Caritas-Gottesdienst-07-03-2026-rotated.jpg 1024w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/Caritas-Gottesdienst-07-03-2026-300x225.jpg 300w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/Caritas-Gottesdienst-07-03-2026-768x576.jpg 768w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/03\/Caritas-Gottesdienst-07-03-2026-400x300.jpg 400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Caritas-Gottesdienst &#8222;Zusammen geht was &#8211; Caritas verbindet Generationen&#8220; am 7. M\u00e4rz 2026<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Weihnachtsgottesdienst_Domicil-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1543\" data-id=\"495\" src=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Weihnachtsgottesdienst_Domicil-scaled.jpg\" alt=\"\" class=\"wp-image-495\"\/><\/a><figcaption class=\"wp-element-caption\">Weihnachtsgottesdienst im Domicil am 17.12.2025<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Bildschirmfoto_2025-11-18_um_230938.png\"><img loading=\"lazy\" decoding=\"async\" width=\"766\" height=\"1024\" data-id=\"492\" src=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Bildschirmfoto_2025-11-18_um_230938-766x1024.png\" alt=\"\" class=\"wp-image-492\" srcset=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Bildschirmfoto_2025-11-18_um_230938-766x1024.png 766w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Bildschirmfoto_2025-11-18_um_230938-224x300.png 224w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Bildschirmfoto_2025-11-18_um_230938-768x1027.png 768w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Bildschirmfoto_2025-11-18_um_230938-1149x1536.png 1149w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Bildschirmfoto_2025-11-18_um_230938.png 1390w\" sizes=\"auto, (max-width: 766px) 100vw, 766px\" \/><\/a><figcaption class=\"wp-element-caption\">Gottesdienst &#8222;Der Engel mit dem goldenen Schl\u00fcssel&#8220;<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Die_Landschaft_am_Jordan-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"433\" height=\"1024\" data-id=\"677\" src=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Die_Landschaft_am_Jordan-433x1024.jpg\" alt=\"\" class=\"wp-image-677\" srcset=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Die_Landschaft_am_Jordan-433x1024.jpg 433w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Die_Landschaft_am_Jordan-127x300.jpg 127w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Die_Landschaft_am_Jordan-768x1815.jpg 768w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Die_Landschaft_am_Jordan-650x1536.jpg 650w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Die_Landschaft_am_Jordan-867x2048.jpg 867w, https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/Die_Landschaft_am_Jordan-scaled.jpg 1083w\" sizes=\"auto, (max-width: 433px) 100vw, 433px\" \/><\/a><figcaption class=\"wp-element-caption\">Die Landschaft am Jordan<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/20251102_105006-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"493\" src=\"https:\/\/www.sanktgabriel.de\/wp-content\/uploads\/2026\/01\/20251102_105006-scaled.jpg\" alt=\"\" class=\"wp-image-493\"\/><\/a><figcaption class=\"wp-element-caption\">Totengedenken an Allerseelen<\/figcaption><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Hier stellt sich die Pfarrgemeinde St. Gabriel in M\u00fcnchen-Haidhausen mit ihren vielf\u00e4ltigen Aktivit\u00e4ten vor. Nehmen Sie sich Zeit f\u00fcr einen Blick auf die Vielfalt der Gemeinde! Wenn Sie sich einbringen wollen, wenden Sie sich bitte an die entsprechenden Verantwortlichen. Wir &hellip; <a href=\"https:\/\/www.sanktgabriel.de\/index.php\/2026\/01\/03\/leben-und-feiern-mit-dem-wort-gottes-veranstaltungsreihe-fuer-ehrenamtliche\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_mc_calendar":[],"footnotes":""},"class_list":["post-64","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.sanktgabriel.de\/index.php\/wp-json\/wp\/v2\/pages\/64","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sanktgabriel.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sanktgabriel.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sanktgabriel.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sanktgabriel.de\/index.php\/wp-json\/wp\/v2\/comments?post=64"}],"version-history":[{"count":33,"href":"https:\/\/www.sanktgabriel.de\/index.php\/wp-json\/wp\/v2\/pages\/64\/revisions"}],"predecessor-version":[{"id":843,"href":"https:\/\/www.sanktgabriel.de\/index.php\/wp-json\/wp\/v2\/pages\/64\/revisions\/843"}],"wp:attachment":[{"href":"https:\/\/www.sanktgabriel.de\/index.php\/wp-json\/wp\/v2\/media?parent=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}